{"id":534,"count":26,"description":"Cedr to ponadczasowy i klasyczny zapach. Jego drzewne nuty s\u0105 cz\u0119sto kojarzone z si\u0142\u0105, pewno\u015bci\u0105 siebie i m\u0119sko\u015bci\u0105. Aromat ten mo\u017ce by\u0107 stosowany w r\u00f3\u017cnych perfumach, od \u015bwie\u017cych i czystych zapach\u00f3w po bardziej intensywne i z\u0142o\u017cone zapachy.\n\nDrzewo cedrowe jest cz\u0119sto mieszane z innymi drzewnymi zapachami, takimi jak drzewo sanda\u0142owe i mech d\u0119bowy, tworz\u0105c ciep\u0142e i zach\u0119caj\u0105ce zapachy. Perfumy na bazie cedru s\u0105 popularnym wyborem w przypadku perfum m\u0119skich, ale mo\u017cna je r\u00f3wnie\u017c znale\u017a\u0107 w perfumach damskich jako wyrafinowany i wyrafinowany zapach.","link":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/","name":"Cedr","slug":"cedr","taxonomy":"natos","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cedr - Perfumessence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cedr - Perfumessence\" \/>\n<meta property=\"og:description\" content=\"Cedr to ponadczasowy i klasyczny zapach. Jego drzewne nuty s\u0105 cz\u0119sto kojarzone z si\u0142\u0105, pewno\u015bci\u0105 siebie i m\u0119sko\u015bci\u0105. Aromat ten mo\u017ce by\u0107 stosowany w r\u00f3\u017cnych perfumach, od \u015bwie\u017cych i czystych zapach\u00f3w po bardziej intensywne i z\u0142o\u017cone zapachy. Drzewo cedrowe jest cz\u0119sto mieszane z innymi drzewnymi zapachami, takimi jak drzewo sanda\u0142owe i mech d\u0119bowy, tworz\u0105c ciep\u0142e i zach\u0119caj\u0105ce zapachy. Perfumy na bazie cedru s\u0105 popularnym wyborem w przypadku perfum m\u0119skich, ale mo\u017cna je r\u00f3wnie\u017c znale\u017a\u0107 w perfumach damskich jako wyrafinowany i wyrafinowany zapach.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/\" \/>\n<meta property=\"og:site_name\" content=\"Perfumessence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/\",\"url\":\"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/\",\"name\":\"Cedr - Perfumessence\",\"isPartOf\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagrindinis\",\"item\":\"https:\/\/perfumessence.eu\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cedr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/#website\",\"url\":\"https:\/\/perfumessence.eu\/pl\/\",\"name\":\"Parfumerin\u0117 esencija\",\"description\":\"Perfume Oils and Sprays\",\"publisher\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/perfumessence.eu\/pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/#organization\",\"name\":\"Parfumerin\u0117 esencija\",\"url\":\"https:\/\/perfumessence.eu\/pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Parfumerin\u0117 esencija\"},\"image\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Parfumerin\u0117-esencija-424160218027238\/\",\"https:\/\/www.youtube.com\/channel\/UC0RI-RLwg1UQwDbAF-7a-MA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cedr - Perfumessence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/","og_locale":"pl_PL","og_type":"article","og_title":"Cedr - Perfumessence","og_description":"Cedr to ponadczasowy i klasyczny zapach. Jego drzewne nuty s\u0105 cz\u0119sto kojarzone z si\u0142\u0105, pewno\u015bci\u0105 siebie i m\u0119sko\u015bci\u0105. Aromat ten mo\u017ce by\u0107 stosowany w r\u00f3\u017cnych perfumach, od \u015bwie\u017cych i czystych zapach\u00f3w po bardziej intensywne i z\u0142o\u017cone zapachy. Drzewo cedrowe jest cz\u0119sto mieszane z innymi drzewnymi zapachami, takimi jak drzewo sanda\u0142owe i mech d\u0119bowy, tworz\u0105c ciep\u0142e i zach\u0119caj\u0105ce zapachy. Perfumy na bazie cedru s\u0105 popularnym wyborem w przypadku perfum m\u0119skich, ale mo\u017cna je r\u00f3wnie\u017c znale\u017a\u0107 w perfumach damskich jako wyrafinowany i wyrafinowany zapach.","og_url":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/","og_site_name":"Perfumessence","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/","url":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/","name":"Cedr - Perfumessence","isPartOf":{"@id":"https:\/\/perfumessence.eu\/pl\/#website"},"breadcrumb":{"@id":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/perfumessence.eu\/pl\/natos\/cedr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagrindinis","item":"https:\/\/perfumessence.eu\/pl\/"},{"@type":"ListItem","position":2,"name":"Cedr"}]},{"@type":"WebSite","@id":"https:\/\/perfumessence.eu\/pl\/#website","url":"https:\/\/perfumessence.eu\/pl\/","name":"Parfumerin\u0117 esencija","description":"Perfume Oils and Sprays","publisher":{"@id":"https:\/\/perfumessence.eu\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perfumessence.eu\/pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/perfumessence.eu\/pl\/#organization","name":"Parfumerin\u0117 esencija","url":"https:\/\/perfumessence.eu\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Parfumerin\u0117 esencija"},"image":{"@id":"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Parfumerin\u0117-esencija-424160218027238\/","https:\/\/www.youtube.com\/channel\/UC0RI-RLwg1UQwDbAF-7a-MA"]}]}},"_links":{"self":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/natos\/534"}],"collection":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/natos"}],"about":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/taxonomies\/natos"}],"wp:post_type":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/product?natos=534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}