{"id":557,"count":6,"description":"Sza\u0142wia ma \u015bwie\u017cy, zio\u0142owy i lekko drzewny aromat, kt\u00f3ry cz\u0119sto opisywany jest jako mieszanka mi\u0119ty, cytryny i kamfory. To wyj\u0105tkowy i niezwykle aromatyczny zapach. Pomaga stworzy\u0107 uspokajaj\u0105c\u0105 atmosfer\u0119 i zapewnia \u015bwie\u017cy zio\u0142owy aromat.","link":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/","name":"M\u0119drzec","slug":"medrzec","taxonomy":"natos","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u0119drzec - Perfumessence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u0119drzec - Perfumessence\" \/>\n<meta property=\"og:description\" content=\"Sza\u0142wia ma \u015bwie\u017cy, zio\u0142owy i lekko drzewny aromat, kt\u00f3ry cz\u0119sto opisywany jest jako mieszanka mi\u0119ty, cytryny i kamfory. To wyj\u0105tkowy i niezwykle aromatyczny zapach. Pomaga stworzy\u0107 uspokajaj\u0105c\u0105 atmosfer\u0119 i zapewnia \u015bwie\u017cy zio\u0142owy aromat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/\" \/>\n<meta property=\"og:site_name\" content=\"Perfumessence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/\",\"url\":\"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/\",\"name\":\"M\u0119drzec - Perfumessence\",\"isPartOf\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagrindinis\",\"item\":\"https:\/\/perfumessence.eu\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u0119drzec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/#website\",\"url\":\"https:\/\/perfumessence.eu\/pl\/\",\"name\":\"Parfumerin\u0117 esencija\",\"description\":\"Perfume Oils and Sprays\",\"publisher\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/perfumessence.eu\/pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/#organization\",\"name\":\"Parfumerin\u0117 esencija\",\"url\":\"https:\/\/perfumessence.eu\/pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Parfumerin\u0117 esencija\"},\"image\":{\"@id\":\"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Parfumerin\u0117-esencija-424160218027238\/\",\"https:\/\/www.youtube.com\/channel\/UC0RI-RLwg1UQwDbAF-7a-MA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u0119drzec - Perfumessence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/","og_locale":"pl_PL","og_type":"article","og_title":"M\u0119drzec - Perfumessence","og_description":"Sza\u0142wia ma \u015bwie\u017cy, zio\u0142owy i lekko drzewny aromat, kt\u00f3ry cz\u0119sto opisywany jest jako mieszanka mi\u0119ty, cytryny i kamfory. To wyj\u0105tkowy i niezwykle aromatyczny zapach. Pomaga stworzy\u0107 uspokajaj\u0105c\u0105 atmosfer\u0119 i zapewnia \u015bwie\u017cy zio\u0142owy aromat.","og_url":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/","og_site_name":"Perfumessence","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/","url":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/","name":"M\u0119drzec - Perfumessence","isPartOf":{"@id":"https:\/\/perfumessence.eu\/pl\/#website"},"breadcrumb":{"@id":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/perfumessence.eu\/pl\/natos\/medrzec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagrindinis","item":"https:\/\/perfumessence.eu\/pl\/"},{"@type":"ListItem","position":2,"name":"M\u0119drzec"}]},{"@type":"WebSite","@id":"https:\/\/perfumessence.eu\/pl\/#website","url":"https:\/\/perfumessence.eu\/pl\/","name":"Parfumerin\u0117 esencija","description":"Perfume Oils and Sprays","publisher":{"@id":"https:\/\/perfumessence.eu\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perfumessence.eu\/pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/perfumessence.eu\/pl\/#organization","name":"Parfumerin\u0117 esencija","url":"https:\/\/perfumessence.eu\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Parfumerin\u0117 esencija"},"image":{"@id":"https:\/\/perfumessence.eu\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Parfumerin\u0117-esencija-424160218027238\/","https:\/\/www.youtube.com\/channel\/UC0RI-RLwg1UQwDbAF-7a-MA"]}]}},"_links":{"self":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/natos\/557"}],"collection":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/natos"}],"about":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/taxonomies\/natos"}],"wp:post_type":[{"href":"https:\/\/perfumessence.eu\/pl\/wp-json\/wp\/v2\/product?natos=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}